{"id":15780,"date":"2022-07-12T09:18:37","date_gmt":"2022-07-12T09:18:37","guid":{"rendered":"https:\/\/www.territory-influence.com\/project\/nano-infuencers-per-pesto-mutti\/"},"modified":"2023-06-26T09:06:05","modified_gmt":"2023-06-26T09:06:05","slug":"nano-infuencers-per-pesto-mutti","status":"publish","type":"project","link":"https:\/\/www.territory-influence.com\/it\/project\/nano-infuencers-per-pesto-mutti\/","title":{"rendered":"Nano infuencer per Pesto Mutti"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Hero&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#FF4E00&#8243; background_image=&#8221;https:\/\/www.territory-influence.com\/wp-content\/uploads\/2020\/12\/circle-background-pattern.png&#8221; custom_padding=&#8221;67px|0px|67.1875px|0px|false|false&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;4%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;3%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16.0&#8243; text_font=&#8221;Roboto|500||on|||||&#8221; text_text_color=&#8221;#353740&#8243; text_font_size=&#8221;16px&#8221; custom_margin=&#8221;||19px|||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>NANO INFLUENCER<\/p>\n<p>[\/et_pb_text][et_pb_text module_class=&#8221;tt-white&#8221; _builder_version=&#8221;4.16.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Roboto|900||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;50px&#8221; header_line_height=&#8221;1.1em&#8221; custom_margin=&#8221;|||&#8221; animation_style=&#8221;fade&#8221; header_font_size_last_edited=&#8221;off|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Case Study<br \/>\n<tt-underline><\/tt-underline>PESTO MUTTI<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Case Study Text&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;110px||18px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-40px||||false|false&#8221; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Roboto|500|||||||&#8221; text_font_size=&#8221;16px&#8221; header_font=&#8221;Roboto|900|||||||&#8221; header_font_size=&#8221;45px&#8221; header_2_font=&#8221;Roboto|900|||||||&#8221; header_2_font_size=&#8221;30px&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<div class=\"item-padd-mob section-text text-block \">\n<div class=\"simple-text md\">\n<p>Abbiamo attiv<span style=\"color: #000000;\">ato <strong>3.000 consumatori<\/strong> in Italia per aiutare <a href=\"https:\/\/mutti-parma.com\/it\/\" target=\"_blank\" rel=\"noopener\">Mutti<\/a> ad aumentare la conoscenza e la reputazione della sua gamma di prodotti a base di pesto al pomodoro: Verde, Rosso e Arancione. Il progetto comprendeva l&#8217;educazione al<\/span> prodotto e la generazione di prove di prodotto e raccomandazioni dei consumatori sia online che offline.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"item-padd-mob section-text text-block \">\n<div class=\"simple-text md\">\n<h2><strong>Sono stati selezionati 3.000 potenziali consumatori<\/strong><\/h2>\n<\/div>\n<\/div>\n<div class=\"item-padd-mob section-text text-block \">\n<div class=\"simple-text md\">\n<p>I 3.000 food lovers consumavano gi\u00e0 sughi pronti ogni settimana, ma il <strong>78% non conosceva il Pesto Mutti prima del progetto<\/strong>. Dopo averli istruiti sui prodotti, li abbiamo invitati a provarli e a condividere la loro esperienza con i loro follower online, ma anche con amici e familiari offline.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"item-padd-mob section-text text-block \">\n<div class=\"simple-text md\">\n<p>Sui loro social media, principalmente su Instagram e Facebook, hanno postato 5.739 contenuti con gli hashtag #PestiDiPomodoroMutti e #MuttiPomodoro (raddoppiando l&#8217;obiettivo iniziale della campagna). Hanno descritto la loro esperienza con il Pesto Mutti e alcuni nano influencer hanno persino condiviso le loro ricette. Alla fine della campagna,<strong>sono riusciti a raggiungere +7,5 milioni di potenziali impressioni sul brand.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"item-padd-mob section-text text-block \">\n<div class=\"simple-text md\">\n<h2><strong>Il potere delle recensioni offline<\/strong><\/h2>\n<\/div>\n<\/div>\n<div class=\"item-padd-mob section-text text-block \">\n<div class=\"simple-text md\">\n<p>Inoltre, hanno organizzato pi\u00f9 di 6.500 <a href=\"https:\/\/www.territory-influence.com\/es\/sampling-de-producto\/\" target=\"_blank\" rel=\"noopener\">eventi con amici e familiari<\/a> in cui tutti hanno provato il prodotto.<strong> In totale sono state effettuate 109.980 prove del prodotto. L&#8217;impatto offline ha raggiunto pi\u00f9 di 799.000 persone, il 78% delle quali non aveva mai provato il prodotto prima.<\/strong> Dopo averlo assaggiato, hanno dichiarato che il Pesto Mutti era migliore dei prodotti della concorrenza.<\/p>\n<p>Al termine del progetto, i nano influencer hanno valutato il prodotto con 8,5\/10 e<span style=\"color: #000000;\"> il <strong>95% ha dichiarato che lo consiglier\u00e0<\/strong>. L&#8217;<\/span>89% ha inoltre dichiarato che acquister\u00e0 Pesto Mutti dopo la campagna.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Scorri in basso per scoprire tutti i risultati ottenuti.<\/b><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_video src=&#8221;https:\/\/youtu.be\/-QqSvyIIPUg&#8221; _builder_version=&#8221;4.16.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Fun Fact Section&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#252422&#8243; custom_margin=&#8221;-126px|||||&#8221; custom_padding=&#8221;110px||50px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_5,1_5,1_5,1_5,1_5&#8243; admin_label=&#8221;Fun Fact&#8221; _builder_version=&#8221;4.16.0&#8243; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;60px||40px|||&#8221; animation_style=&#8221;zoom&#8221; animation_direction=&#8221;top&#8221; animation_intensity_zoom=&#8221;10%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_number_counter title=&#8221;Nano influencers&#8221; number=&#8221;3.000&#8243; percent_sign=&#8221;off&#8221; _builder_version=&#8221;4.16.0&#8243; title_font=&#8221;Roboto|700|||||||&#8221; title_text_color=&#8221;#ffffff&#8221; title_font_size=&#8221;18px&#8221; number_font=&#8221;Roboto|700|||||||&#8221; number_text_color=&#8221;#ffffff&#8221; number_font_size=&#8221;50px&#8221; number_line_height=&#8221;90px&#8221; animation_style=&#8221;zoom&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_number_counter title=&#8221;Contenuti sui social media&#8221; number=&#8221;5.739&#8243; percent_sign=&#8221;off&#8221; _builder_version=&#8221;4.16.0&#8243; title_font=&#8221;Roboto|700|||||||&#8221; title_text_color=&#8221;#ffffff&#8221; title_font_size=&#8221;18px&#8221; number_font=&#8221;Roboto|700|||||||&#8221; number_text_color=&#8221;#ffffff&#8221; number_font_size=&#8221;50px&#8221; number_line_height=&#8221;90px&#8221; animation_style=&#8221;zoom&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_number_counter title=&#8221;Potenziali impressioni sul brand&#8221; number=&#8221;+7.5M&#8221; percent_sign=&#8221;off&#8221; _builder_version=&#8221;4.16.0&#8243; title_font=&#8221;Roboto|700|||||||&#8221; title_text_color=&#8221;#ffffff&#8221; title_font_size=&#8221;18px&#8221; number_font=&#8221;Roboto|700|||||||&#8221; number_text_color=&#8221;#ffffff&#8221; number_font_size=&#8221;50px&#8221; number_line_height=&#8221;90px&#8221; custom_margin=&#8221;|-20px||-20px|false|false&#8221; animation_style=&#8221;zoom&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_number_counter title=&#8221;Reach offline&#8221; number=&#8221;+799K&#8221; percent_sign=&#8221;off&#8221; _builder_version=&#8221;4.16.0&#8243; title_font=&#8221;Roboto|700|||||||&#8221; title_text_color=&#8221;#ffffff&#8221; title_font_size=&#8221;18px&#8221; number_font=&#8221;Roboto|700|||||||&#8221; number_text_color=&#8221;#ffffff&#8221; number_font_size=&#8221;50px&#8221; number_line_height=&#8221;90px&#8221; custom_margin=&#8221;||||false|false&#8221; animation_style=&#8221;zoom&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_number_counter title=&#8221;Prove di prodotto&#8221; number=&#8221;+109K&#8221; percent_sign=&#8221;off&#8221; _builder_version=&#8221;4.16.0&#8243; title_font=&#8221;Roboto|700|||||||&#8221; title_text_color=&#8221;#ffffff&#8221; title_font_size=&#8221;18px&#8221; number_font=&#8221;Roboto|700|||||||&#8221; number_text_color=&#8221;#ffffff&#8221; number_font_size=&#8221;50px&#8221; number_line_height=&#8221;90px&#8221; animation_style=&#8221;zoom&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_number_counter][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text module_class=&#8221;tt-black&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Roboto|900|||||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;35px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1> CONDIVIDI SU<\/h1>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/www.linkedin.com\/&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Linkedin&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#FF4E00&#8243; button_border_width=&#8221;8px&#8221; button_border_color=&#8221;#FF4E00&#8243; button_border_radius=&#8221;0px&#8221; button_font=&#8221;Roboto|700|||||||&#8221; button_icon=&#8221;&#x24;||divi||400&#8243; button_icon_color=&#8221;#ffffff&#8221; button_on_hover=&#8221;off&#8221; custom_margin=&#8221;-21px|||||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abbiamo attivato 3.000 consumatori in Italia per aiutare Mutti ad aumentare la conoscenza e la reputazione della sua gamma di prodotti&#8230;<\/p>\n","protected":false},"author":19,"featured_media":15770,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"project_category":[204],"project_tag":[388,387,545,598,720,596,597],"class_list":["post-15780","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-food-beverages-it","project_tag-case-study-it","project_tag-influencer-campaign-it","project_tag-influencer-marketing-it-2","project_tag-influencer-marketing-case-study-it","project_tag-le-migliori-campagne-di-influencer","project_tag-nano-influencer-it-2","project_tag-the-best-influencers-marketing-campaign-examples-it"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.territory-influence.com\/it\/wp-json\/wp\/v2\/project\/15780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.territory-influence.com\/it\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www.territory-influence.com\/it\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/www.territory-influence.com\/it\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.territory-influence.com\/it\/wp-json\/wp\/v2\/comments?post=15780"}],"version-history":[{"count":13,"href":"https:\/\/www.territory-influence.com\/it\/wp-json\/wp\/v2\/project\/15780\/revisions"}],"predecessor-version":[{"id":24944,"href":"https:\/\/www.territory-influence.com\/it\/wp-json\/wp\/v2\/project\/15780\/revisions\/24944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.territory-influence.com\/it\/wp-json\/wp\/v2\/media\/15770"}],"wp:attachment":[{"href":"https:\/\/www.territory-influence.com\/it\/wp-json\/wp\/v2\/media?parent=15780"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/www.territory-influence.com\/it\/wp-json\/wp\/v2\/project_category?post=15780"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/www.territory-influence.com\/it\/wp-json\/wp\/v2\/project_tag?post=15780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}